{"id":258,"date":"2024-03-27T10:30:28","date_gmt":"2024-03-27T10:30:28","guid":{"rendered":"https:\/\/www.plataformaestepadelhuerva.es\/?page_id=258"},"modified":"2024-03-27T11:51:14","modified_gmt":"2024-03-27T11:51:14","slug":"encuentro-cultural-por-la-racionalidad-energetica","status":"publish","type":"page","link":"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/encuentro-cultural-por-la-racionalidad-energetica\/","title":{"rendered":"Encuentro Cultural por la Racionalidad Energ\u00e9tica"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"kubio-page-with-right-sidebar","meta":{"saved_in_kubio":true,"footnotes":""},"class_list":["post-258","page","type-page","status-publish","hentry"],"kubio_ai_page_context":{"short_desc":"","purpose":"general"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Encuentro Cultural por la Racionalidad Energ\u00e9tica - Plataforma en defensa de la estepa del Huerva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/encuentro-cultural-por-la-racionalidad-energetica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encuentro Cultural por la Racionalidad Energ\u00e9tica - Plataforma en defensa de la estepa del Huerva\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/encuentro-cultural-por-la-racionalidad-energetica\/\" \/>\n<meta property=\"og:site_name\" content=\"Plataforma en defensa de la estepa del Huerva\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-27T11:51:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.plataformaestepadelhuerva.es\\\/index.php\\\/encuentro-cultural-por-la-racionalidad-energetica\\\/\",\"url\":\"https:\\\/\\\/www.plataformaestepadelhuerva.es\\\/index.php\\\/encuentro-cultural-por-la-racionalidad-energetica\\\/\",\"name\":\"Encuentro Cultural por la Racionalidad Energ\u00e9tica - Plataforma en defensa de la estepa del Huerva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plataformaestepadelhuerva.es\\\/#website\"},\"datePublished\":\"2024-03-27T10:30:28+00:00\",\"dateModified\":\"2024-03-27T11:51:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.plataformaestepadelhuerva.es\\\/index.php\\\/encuentro-cultural-por-la-racionalidad-energetica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.plataformaestepadelhuerva.es\\\/index.php\\\/encuentro-cultural-por-la-racionalidad-energetica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.plataformaestepadelhuerva.es\\\/index.php\\\/encuentro-cultural-por-la-racionalidad-energetica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.plataformaestepadelhuerva.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encuentro Cultural por la Racionalidad Energ\u00e9tica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.plataformaestepadelhuerva.es\\\/#website\",\"url\":\"https:\\\/\\\/www.plataformaestepadelhuerva.es\\\/\",\"name\":\"Plataforma en defensa de la estepa del Huerva\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.plataformaestepadelhuerva.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encuentro Cultural por la Racionalidad Energ\u00e9tica - Plataforma en defensa de la estepa del Huerva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/encuentro-cultural-por-la-racionalidad-energetica\/","og_locale":"es_ES","og_type":"article","og_title":"Encuentro Cultural por la Racionalidad Energ\u00e9tica - Plataforma en defensa de la estepa del Huerva","og_url":"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/encuentro-cultural-por-la-racionalidad-energetica\/","og_site_name":"Plataforma en defensa de la estepa del Huerva","article_modified_time":"2024-03-27T11:51:14+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/encuentro-cultural-por-la-racionalidad-energetica\/","url":"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/encuentro-cultural-por-la-racionalidad-energetica\/","name":"Encuentro Cultural por la Racionalidad Energ\u00e9tica - Plataforma en defensa de la estepa del Huerva","isPartOf":{"@id":"https:\/\/www.plataformaestepadelhuerva.es\/#website"},"datePublished":"2024-03-27T10:30:28+00:00","dateModified":"2024-03-27T11:51:14+00:00","breadcrumb":{"@id":"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/encuentro-cultural-por-la-racionalidad-energetica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.plataformaestepadelhuerva.es\/index.php\/encuentro-cultural-por-la-racionalidad-energetica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/encuentro-cultural-por-la-racionalidad-energetica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.plataformaestepadelhuerva.es\/"},{"@type":"ListItem","position":2,"name":"Encuentro Cultural por la Racionalidad Energ\u00e9tica"}]},{"@type":"WebSite","@id":"https:\/\/www.plataformaestepadelhuerva.es\/#website","url":"https:\/\/www.plataformaestepadelhuerva.es\/","name":"Plataforma en defensa de la estepa del Huerva","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.plataformaestepadelhuerva.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/wp-json\/wp\/v2\/pages\/258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/wp-json\/wp\/v2\/comments?post=258"}],"version-history":[{"count":5,"href":"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/wp-json\/wp\/v2\/pages\/258\/revisions"}],"predecessor-version":[{"id":313,"href":"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/wp-json\/wp\/v2\/pages\/258\/revisions\/313"}],"wp:attachment":[{"href":"https:\/\/www.plataformaestepadelhuerva.es\/index.php\/wp-json\/wp\/v2\/media?parent=258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}